{"id":137126,"date":"2024-06-21T09:40:55","date_gmt":"2024-06-21T07:40:55","guid":{"rendered":"https:\/\/castelldor.com\/castell-dor-imperial-gran-reserva-brut-nature-2018-medalla-dor-als-premis-decanter\/"},"modified":"2024-07-01T12:15:30","modified_gmt":"2024-07-01T10:15:30","slug":"castell-dor-imperial-gran-reserva-brut-nature-2018-medalla-dor-als-premis-decanter","status":"publish","type":"post","link":"https:\/\/castelldor.com\/es\/castell-dor-imperial-gran-reserva-brut-nature-2018-medalla-dor-als-premis-decanter\/","title":{"rendered":"Castell d\u2019Or Imperial Gran Reserva, Medalla de Oro en los Decanter"},"content":{"rendered":"<p><strong><em>El grup ha obtenido un total de cinco medallas en el prestigioso premi brit\u00e1nico\u00a0<\/em><\/strong><\/p>\n<p>El grupo Castell d&#8217;Or, una referencia destacada en la elaboraci\u00f3n de cavas de alta calidad, ha obtenido un reconocimiento significativo a los <a href=\"https:\/\/www.decanter.com\/decanter-awards\/\"><strong>Decanter World Wine Awards<\/strong><\/a>. Sus cavas han sido galardonados con cinco medallas en este prestigioso concurso internacional. Ha sido el Cava <a href=\"https:\/\/castelldor.com\/es\/producto\/cava-brut-nature-gran-reserva-castell-dor\/\"><strong>Castell d&#8217;Or Imperial Gran Reserva Brut Nature 2018<\/strong><\/a> el que ha obtenido una medalla de Oro. Adem\u00e1s, Castell d&#8217;Or ha obtenido tres medallas de plata y una de bronce por sus diferentes propuestas enol\u00f3gicas.<\/p>\n<p>&nbsp;<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-137114 size-large\" src=\"https:\/\/castelldor.com\/wp-content\/uploads\/2024\/06\/CASTELLDOR245-scaled-e1718955615923-1024x491.jpg\" alt=\"\" width=\"1024\" height=\"491\" srcset=\"https:\/\/castelldor.com\/wp-content\/uploads\/2024\/06\/CASTELLDOR245-scaled-e1718955615923-1024x491.jpg 1024w, https:\/\/castelldor.com\/wp-content\/uploads\/2024\/06\/CASTELLDOR245-scaled-e1718955615923-300x144.jpg 300w, https:\/\/castelldor.com\/wp-content\/uploads\/2024\/06\/CASTELLDOR245-scaled-e1718955615923-768x368.jpg 768w, https:\/\/castelldor.com\/wp-content\/uploads\/2024\/06\/CASTELLDOR245-scaled-e1718955615923-1536x736.jpg 1536w, https:\/\/castelldor.com\/wp-content\/uploads\/2024\/06\/CASTELLDOR245-scaled-e1718955615923-600x288.jpg 600w, https:\/\/castelldor.com\/wp-content\/uploads\/2024\/06\/CASTELLDOR245-scaled-e1718955615923.jpg 1706w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h2>Listado de premios 2024<\/h2>\n<ul>\n<li>GOLD MEDAL con 95 Puntos Castell d&#8217;Or Imperial Grande Reserva Brut Nature 2018<\/li>\n<li>SILVER MEDAL con 91 Puntos Castell d&#8217;Or Brut Imperial<\/li>\n<li>SILVER MEDAL con 90 Puntos Flama d&#8217;Or Brut Rosat<\/li>\n<li>SILVER MEDAL con 90 Puntos Flama d&#8217;Or Brut<\/li>\n<li>BRONCE MEDAL con 88 Puntos Cabaret Brut Org\u00e0nic<\/li>\n<\/ul>\n<h2><strong>Decanter World Wine Awards<\/strong><\/h2>\n<p>El <strong>Decanter World Wine Awards<\/strong> es uno de los concursos m\u00e1s prestigiosos y respetados en el mundo del vino y del cava. Los ganadores son seleccionados mediante un riguroso proceso de evaluaci\u00f3n realizado por un panel de expertos reconocidos internacionalmente. Este reconocimiento es testigo de la excelencia y esfuerzo de Castell d&#8217;Or en la elaboraci\u00f3n de cavas de calidad superior. En respuesta a este hecho destacado, Jordi Amell, CEO de Castell d&#8217;Or, ha destacado que: \u00ab<strong>estamos muy orgullosos de estos galardones en el mercado brit\u00e1nico y de la evoluci\u00f3n que hemos tenido, mejorando notablemente nuestra posici\u00f3n respecto a a\u00f1os anteriores<\/strong>\u201d. Amell ha a\u00f1adido que \u201c<strong>este premio reconoce nuestra pasi\u00f3n y esfuerzo por presentar cavas excelentes, elaborados en nuestra tierra y con un car\u00e1cter muy definido que nos destaca al panorama nacional e internacional\u201d<\/strong>.<\/p>\n<p>Estos premios se a\u00f1aden a los galardones m\u00e1s recientes obtenidos a nivel nacional e internacional. Estos reconocimientos se pueden consultar <a href=\"https:\/\/castelldor.com\/es\/premios-y-reconocimientos\/?_sft_any=2024-es\">aqu\u00ed<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2>Castell d&#8217;Or, la uni\u00f3n de 16 cooperativas del territorio catal\u00e1n<\/h2>\n<p>Castell d&#8217;Or nace el 2006 de la uni\u00f3n de diferentes cooperativas que trabajan la tierra con pasi\u00f3n y respeto. A estas alturas, son un total de 16 las bodegas que forman parte de uno de los grupos m\u00e1s representativos de Catalu\u00f1a. Apuestan para unir sus esfuerzos y conocimientos en los procesos de producci\u00f3n, elaboraci\u00f3n, envasado y distribuci\u00f3n de vinos, cava y aceites elevando el est\u00e1ndar de calidad de sus productos hasta obtener el reconocimiento y el prestigio en todo el mundo de sus marcas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El grup ha obtenido un total de cinco medallas en el prestigioso premi brit\u00e1nico\u00a0 El grupo Castell d&#8217;Or, una referencia destacada en la elaboraci\u00f3n de cavas de alta calidad, ha obtenido un reconocimiento significativo a los Decanter World Wine Awards. Sus cavas han sido galardonados con cinco medallas en este prestigioso concurso internacional. Ha sido&hellip;&nbsp;<a href=\"https:\/\/castelldor.com\/es\/castell-dor-imperial-gran-reserva-brut-nature-2018-medalla-dor-als-premis-decanter\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Castell d\u2019Or Imperial Gran Reserva, Medalla de Oro en los Decanter<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":137113,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":70,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","footnotes":""},"categories":[44],"tags":[],"class_list":["post-137126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad"],"acf":[],"_links":{"self":[{"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/posts\/137126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/comments?post=137126"}],"version-history":[{"count":5,"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/posts\/137126\/revisions"}],"predecessor-version":[{"id":137139,"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/posts\/137126\/revisions\/137139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/media\/137113"}],"wp:attachment":[{"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/media?parent=137126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/categories?post=137126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/castelldor.com\/es\/wp-json\/wp\/v2\/tags?post=137126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}